{"id":2,"date":"2020-06-02T00:09:03","date_gmt":"2020-06-02T05:09:03","guid":{"rendered":"http:\/?page_id=2"},"modified":"2020-09-02T17:47:03","modified_gmt":"2020-09-02T22:47:03","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/eljuegodepelota.com\/en\/","title":{"rendered":"Home: El Juego de Pelota: Pasado y Futuro"},"content":{"rendered":"<p class=\"has-text-align-center has-vivid-red-color has-text-color has-large-font-size wp-block-paragraph\"><span class=\"has-inline-color has-vivid-red-color\">El Juego de Pelota como Juego<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large is-style-default\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"456\" src=\"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego.jpg?resize=1024%2C456&#038;ssl=1\" alt=\"Proyecci\u00f3n futurista de una cancha Juego de Pelota\" class=\"wp-image-126\" srcset=\"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?resize=1024%2C456&amp;ssl=1 1024w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?resize=300%2C134&amp;ssl=1 300w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?resize=768%2C342&amp;ssl=1 768w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?resize=1536%2C684&amp;ssl=1 1536w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?resize=2048%2C912&amp;ssl=1 2048w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><span class=\"has-inline-color has-luminous-vivid-orange-color\">De los Olmecas a los Mexicanos, de los Mexicanos al Mundo<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-drop-cap has-very-light-gray-background-color has-background wp-block-paragraph\">Aproximadamente para 1500 A.C. los <a href=\"https:\/\/es.wikipedia.org\/wiki\/Olmeca\" target=\"_blank\" rel=\"noreferrer noopener\">Olmecas<\/a> establecidos en lo que hoy es el sureste de M\u00e9xico, hab\u00edan inventado la pelota de hule &#8211; material desconocido en el resto del mundo &#8211; y construido canchas para jugar con ella: El juego de pelota hab\u00eda nacido.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El juego fu\u00e9 adoptado por Teotihuacanos, Mayas, Aztecas y pr\u00e1cticamente por todas las culturas mesoamericanas que continuaron perfeccion\u00e1ndolo durante 3000 a\u00f1os. Existen m\u00e1s de 2500 restos de las canchas abandonadas o destru\u00eddas hace siglos desde Arizona hasta Honduras y El Salvador.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En t\u00e9rminos del tiempo de su existencia, el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Juego_de_pelota_mesoamericano\" target=\"_blank\" rel=\"noreferrer noopener\">juego de pelota mesoamericano<\/a> fu\u00e9 el deporte de pelota m\u00e1s exitoso de la humanidad hasta el a\u00f1o de 1521 en que fu\u00e9 vetado en su totalidad por los conquistadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El deporte nacional se volvi\u00f3 un juego prohibido al tiempo que el hule y las pelotas llegaron a Europa para revitalizar los deportes del viejo continente y del planeta, habi\u00e9ndose despu\u00e9s olvidado donde y como se origin\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este espacio pretende acercarnos a la vivencia del juego, fantasear lo que ser\u00eda la experiencia hoy en d\u00eda de haber continuado su pr\u00e1ctica en los espacios dise\u00f1ados para ello. Los <a href=\"https:\/\/eljuegodepelota.com\/en\/capitulos-blog\/\"><span style=\"text-decoration: underline;\">art\u00edculos<\/span> <\/a> que desgranan el juego para entenderlo est\u00e1n divididos en tres principales per\u00edodos: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/eljuegodepelota.com\/wp-admin\/post.php?post=48&amp;action=edit\">El Juego de Pelota Original:<\/a> desde su nacimiento hasta el fin del desarrollo milenario de las canchas en Mesoam\u00e9rica. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/eljuegodepelota.com\/wp-admin\/post.php?post=541&amp;action=edit\">Los Guardianes de la Tradici\u00f3n:<\/a> su subsistencia en la regi\u00f3n los siguientes 500 a\u00f1os desde la conquista hasta nuestros d\u00edas.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/eljuegodepelota.com\/wp-admin\/post.php?post=547&amp;action=edit\">El Nuevo Juego:<\/a> todo lo que es actualmente y podr\u00eda llegar a ser a partir del siglo XXI. <\/li><\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Es necesario aclarar que este blog no est\u00e1 orientado hacia los aspectos religiosos, rituales, pol\u00edticos, mitol\u00f3gicos, hist\u00f3ricos, arqueol\u00f3gicos o antropol\u00f3gicos del juego, ya que han sido ampliamente estudiados, aunque enlistamos aqu\u00ed algunas<a href=\"https:\/\/eljuegodepelota.com\/en\/bibliografia\/\"> <span style=\"text-decoration: underline;\">referencias<\/span><\/a>. <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuestro enfoque es l\u00fadico y deportivo, <\/strong>el juego como un juego y as\u00ed imaginar las posibilidades del mejor juego de pelota que ha existido, orgullo para los mexicanos. En 2008 los juegos de pelota de origen prehisp\u00e1nico fueron declarados Patrimonio Cultural Intangible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuestro prop\u00f3sito es promover el resurgimiento moderno del juego para proyectarlo hacia el futuro.<\/strong> Para ello, vamos a explorar los principales aspectos deportivos: las canchas, las pelotas, los accesorios conocidos y los propuestos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja.jpg?resize=589%2C351&#038;ssl=1\" alt=\"Propuesta de cancha de juego de pelota para ni\u00f1os y j\u00f3venes\" class=\"wp-image-489\" width=\"589\" height=\"351\" srcset=\"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja-scaled.jpg?resize=1024%2C610&amp;ssl=1 1024w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja-scaled.jpg?resize=300%2C179&amp;ssl=1 300w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja-scaled.jpg?resize=768%2C457&amp;ssl=1 768w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja-scaled.jpg?resize=1536%2C915&amp;ssl=1 1536w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja-scaled.jpg?resize=2048%2C1220&amp;ssl=1 2048w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/07\/Yagul-Plastico-BW-y-Naranja-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:112px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><span style=\"color:#a55742\" class=\"has-inline-color\">&#8220;Si bien el nuevo habitante del pa\u00eds nunca volver\u00e1 a ser el de anta\u00f1o, necesita saber que dispone de un patrimonio que puede disfrutar y digno de orgullo&#8230; Esta heredad es por lo tanto, un logro de siempre y para siempre. No pertenece totalmente ni al pasado ni al futuro, dos tiempos muy remotos. Es un hito m\u00e1s alcanzado por el hombre.&#8221;<\/span><\/p><p><span style=\"color:#a55742\" class=\"has-inline-color\"><strong><a href=\"https:\/\/eljuegodepelota.com\/en\/citas\/\">Arturo Oliveros<\/a><\/strong><\/span><\/p><\/blockquote>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1.jpg?resize=438%2C277&#038;ssl=1\" alt=\"Cancha de juego de pelota de manzanilla\" class=\"wp-image-416\" width=\"438\" height=\"277\" srcset=\"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1-scaled.jpg?resize=1024%2C648&amp;ssl=1 1024w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1-scaled.jpg?resize=300%2C190&amp;ssl=1 300w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1-scaled.jpg?resize=768%2C486&amp;ssl=1 768w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1-scaled.jpg?resize=1536%2C972&amp;ssl=1 1536w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1-scaled.jpg?resize=2048%2C1296&amp;ssl=1 2048w, https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Manzanilla-1-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>El Juego de Pelota como Juego De los Olmecas a los Mexicanos, de los Mexicanos al Mundo Aproximadamente para 1500 A.C. los Olmecas establecidos en lo que hoy es el sureste de M\u00e9xico, hab\u00edan inventado la pelota de hule &#8211; material desconocido en el resto del mundo &#8211; y construido canchas para jugar con ella: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":126,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home: El Juego de Pelota: Pasado y Futuro : El Juego de Pelota<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eljuegodepelota.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home: El Juego de Pelota: Pasado y Futuro : El Juego de Pelota\" \/>\n<meta property=\"og:description\" content=\"El Juego de Pelota como Juego De los Olmecas a los Mexicanos, de los Mexicanos al Mundo Aproximadamente para 1500 A.C. los Olmecas establecidos en lo que hoy es el sureste de M\u00e9xico, hab\u00edan inventado la pelota de hule &#8211; material desconocido en el resto del mundo &#8211; y construido canchas para jugar con ella: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eljuegodepelota.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"El Juego de Pelota\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-02T22:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/\",\"url\":\"https:\\\/\\\/eljuegodepelota.com\\\/\",\"name\":\"Home: El Juego de Pelota: Pasado y Futuro : El Juego de Pelota\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eljuegodepelota.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1\",\"datePublished\":\"2020-06-02T05:09:03+00:00\",\"dateModified\":\"2020-09-02T22:47:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eljuegodepelota.com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eljuegodepelota.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eljuegodepelota.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1\",\"width\":2560,\"height\":1140},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eljuegodepelota.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home: El Juego de Pelota: Pasado y Futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#website\",\"url\":\"https:\\\/\\\/eljuegodepelota.com\\\/\",\"name\":\"El Juego de Pelota\",\"description\":\"Un regalo de Mexico al mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#\\\/schema\\\/person\\\/04264a9f6e446cabed789f1d58df273b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eljuegodepelota.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/eljuegodepelota.com\\\/#\\\/schema\\\/person\\\/04264a9f6e446cabed789f1d58df273b\",\"name\":\"pepestephens1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g\",\"caption\":\"pepestephens1\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home: El Juego de Pelota: Pasado y Futuro : El Juego de Pelota","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eljuegodepelota.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Home: El Juego de Pelota: Pasado y Futuro : El Juego de Pelota","og_description":"El Juego de Pelota como Juego De los Olmecas a los Mexicanos, de los Mexicanos al Mundo Aproximadamente para 1500 A.C. los Olmecas establecidos en lo que hoy es el sureste de M\u00e9xico, hab\u00edan inventado la pelota de hule &#8211; material desconocido en el resto del mundo &#8211; y construido canchas para jugar con ella: [&hellip;]","og_url":"https:\/\/eljuegodepelota.com\/en\/","og_site_name":"El Juego de Pelota","article_modified_time":"2020-09-02T22:47:03+00:00","og_image":[{"width":2560,"height":1140,"url":"https:\/\/i2.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eljuegodepelota.com\/","url":"https:\/\/eljuegodepelota.com\/","name":"Home: El Juego de Pelota: Pasado y Futuro : El Juego de Pelota","isPartOf":{"@id":"https:\/\/eljuegodepelota.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eljuegodepelota.com\/#primaryimage"},"image":{"@id":"https:\/\/eljuegodepelota.com\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1","datePublished":"2020-06-02T05:09:03+00:00","dateModified":"2020-09-02T22:47:03+00:00","breadcrumb":{"@id":"https:\/\/eljuegodepelota.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eljuegodepelota.com\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eljuegodepelota.com\/#primaryimage","url":"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eljuegodepelota.com\/wp-content\/uploads\/2020\/06\/Extrude-Maqueta-En-Fuego-scaled.jpg?fit=2560%2C1140&ssl=1","width":2560,"height":1140},{"@type":"BreadcrumbList","@id":"https:\/\/eljuegodepelota.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eljuegodepelota.com\/"},{"@type":"ListItem","position":2,"name":"Home: El Juego de Pelota: Pasado y Futuro"}]},{"@type":"WebSite","@id":"https:\/\/eljuegodepelota.com\/#website","url":"https:\/\/eljuegodepelota.com\/","name":"El Juego de Pelota","description":"Un regalo de Mexico al mundo","publisher":{"@id":"https:\/\/eljuegodepelota.com\/#\/schema\/person\/04264a9f6e446cabed789f1d58df273b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eljuegodepelota.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/eljuegodepelota.com\/#\/schema\/person\/04264a9f6e446cabed789f1d58df273b","name":"pepestephens1","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g","caption":"pepestephens1"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/8fed948dabe8c958e3cad8a798ef5b24883d99112b99be0650046a99d44d985a?s=96&d=mm&r=g"}}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/Pc3hev-2","_links":{"self":[{"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":5,"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":658,"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/pages\/2\/revisions\/658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/media\/126"}],"wp:attachment":[{"href":"https:\/\/eljuegodepelota.com\/en\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}